{"id":17,"count":3,"description":"","link":"https:\/\/www.sandiegopersonalinjuryattorney.pro\/law\/category\/careless-driving\/","name":"careless driving","slug":"careless-driving","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/www.sandiegopersonalinjuryattorney.pro\/law\/wp-json\/wp\/v2\/categories\/17","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sandiegopersonalinjuryattorney.pro\/law\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/www.sandiegopersonalinjuryattorney.pro\/law\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/www.sandiegopersonalinjuryattorney.pro\/law\/wp-json\/wp\/v2\/posts?categories=17"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}