{"id":21,"count":2,"description":"","link":"https:\/\/www.sandiegopersonalinjuryattorney.pro\/law\/category\/dog-bite\/","name":"dog bite","slug":"dog-bite","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/www.sandiegopersonalinjuryattorney.pro\/law\/wp-json\/wp\/v2\/categories\/21","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sandiegopersonalinjuryattorney.pro\/law\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/www.sandiegopersonalinjuryattorney.pro\/law\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/www.sandiegopersonalinjuryattorney.pro\/law\/wp-json\/wp\/v2\/posts?categories=21"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}