{"id":42,"count":28,"description":"","link":"https:\/\/www.sandiegopersonalinjuryattorney.pro\/law\/category\/wrongful-death\/","name":"wrongful death","slug":"wrongful-death","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/www.sandiegopersonalinjuryattorney.pro\/law\/wp-json\/wp\/v2\/categories\/42","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sandiegopersonalinjuryattorney.pro\/law\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/www.sandiegopersonalinjuryattorney.pro\/law\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/www.sandiegopersonalinjuryattorney.pro\/law\/wp-json\/wp\/v2\/posts?categories=42"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}